{"id":1599,"date":"2011-02-18T10:23:25","date_gmt":"2011-02-18T14:53:25","guid":{"rendered":"http:\/\/www.danielpradilla.info\/blog\/?p=1599"},"modified":"2010-12-17T16:39:13","modified_gmt":"2010-12-17T21:09:13","slug":"como-hacer-una-presentacion-efectiva-con-450-laminas","status":"publish","type":"post","link":"https:\/\/www.danielpradilla.info\/blog\/como-hacer-una-presentacion-efectiva-con-450-laminas\/","title":{"rendered":"C\u00c3\u00b3mo hacer una presentaci\u00c3\u00b3n efectiva con 450 l\u00c3\u00a1minas"},"content":{"rendered":"<p><object classid=\"clsid:d27cdb6e-ae6d-11cf-96b8-444553540000\" width=\"425\" height=\"350\" codebase=\"http:\/\/download.macromedia.com\/pub\/shockwave\/cabs\/flash\/swflash.cab#version=6,0,40,0\"><param name=\"wmode\" value=\"transparent\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/bt9F7tKcZcU\" \/><\/object><\/p>\n<p><a href=\"http:\/\/www.youtube.com\/watch?v=bt9F7tKcZcU\">Y<\/a><a href=\"http:\/\/www.youtube.com\/watch?v=bt9F7tKcZcU\">ouTube &#8211; Google Demo Slam: Epic Docs Animation<\/a>.<\/p>\n<p>Siempre que escribo o hablo sobre <a href=\"\/blog\/?p=1545\" target=\"_blank\">c\u00c3\u00b3mo hacer una presentaci\u00c3\u00b3n efectiva<\/a>, traigo a colaci\u00c3\u00b3n la ley del 10\/20\/30 de Kawasaki y en espec\u00c3\u00adfico la parte del &#8220;10&#8221; de esa regla:\u00a0nunca, nunca hagas una presentaci\u00c3\u00b3n de m\u00c3\u00a1s de 10 l\u00c3\u00a1minas.<\/p>\n<p><a href=\"\/blog\/?p=1596\" target=\"_blank\">A menos que seas Lessig<\/a>, o est\u00c3\u00a9s demostrando lo poderosa que es tu herramienta de presentaci\u00c3\u00b3n, como en el caso de <a href=\"http:\/\/www.youtube.com\/watch?v=bt9F7tKcZcU\" target=\"_blank\">este excelente Google Demo<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>YouTube &#8211; Google Demo Slam: Epic Docs Animation. Siempre que escribo o hablo sobre c\u00c3\u00b3mo hacer una presentaci\u00c3\u00b3n efectiva, traigo a colaci\u00c3\u00b3n la ley del 10\/20\/30 de Kawasaki y en espec\u00c3\u00adfico la parte del &#8220;10&#8221; de esa regla:\u00a0nunca, nunca hagas una presentaci\u00c3\u00b3n de m\u00c3\u00a1s de 10 l\u00c3\u00a1minas. A menos que seas Lessig, o est\u00c3\u00a9s demostrando&hellip; <a class=\"more-link\" href=\"https:\/\/www.danielpradilla.info\/blog\/como-hacer-una-presentacion-efectiva-con-450-laminas\/\">Continue reading <span class=\"screen-reader-text\">C\u00c3\u00b3mo hacer una presentaci\u00c3\u00b3n efectiva con 450 l\u00c3\u00a1minas<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[153,152],"tags":[38,77,119,120,130],"class_list":["post-1599","post","type-post","status-publish","format-standard","hentry","category-controldeproyectos","category-ventas","tag-como-hacer-presentaciones","tag-keynote","tag-powerpoint","tag-presentaciones","tag-secretos-de-presentaciones","entry"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p1tlzy-pN","jetpack_sharing_enabled":true,"jetpack-related-posts":[{"id":1596,"url":"https:\/\/www.danielpradilla.info\/blog\/como-hacer-una-presentacion-efectiva-con-250-laminas\/","url_meta":{"origin":1599,"position":0},"title":"C\u00c3\u00b3mo hacer una presentaci\u00c3\u00b3n efectiva con 250 l\u00c3\u00a1minas","author":"Daniel Pradilla","date":"25\/01\/2011","format":false,"excerpt":"Hace unas semanas, vi a Lawrence Lessig dar la presentaci\u00c3\u00b3n Freeing Culture to be Culture, en el CCCB. Si tienes un mediano inter\u00c3\u00a9s por las t\u00c3\u00a9cnicas para hablar en p\u00c3\u00bablico, Lessig es un espect\u00c3\u00a1culo que hay que ver. Su estilo va en contra de lo que todos recomiendan en cuanto\u2026","rel":"","context":"In &quot;Ventas&quot;","block_context":{"text":"Ventas","link":"https:\/\/www.danielpradilla.info\/blog\/category\/ventas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.afinidades.org\/wp-content\/uploads\/2010\/10\/presentation-zen-book.jpeg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1707,"url":"https:\/\/www.danielpradilla.info\/blog\/como-hacer-una-presentacion-efectiva-iii-los-finales\/","url_meta":{"origin":1599,"position":1},"title":"C\u00c3\u00b3mo hacer una presentaci\u00c3\u00b3n efectiva, III &#8211; Los finales","author":"Daniel Pradilla","date":"01\/01\/2012","format":false,"excerpt":"Ya dominaste el arte de transformar tu mensaje en una historia. Inclusive lograste crear una versi\u00c3\u00b3n de 15 segundos de tu idea. Pero cuando terminas tu discurso, la gente no se entera de que has terminado. No hay aplausos. Quiz\u00c3\u00a1s tengas un problema para terminar. La mayor\u00c3\u00ada de nosotros somos\u2026","rel":"","context":"In &quot;Ventas&quot;","block_context":{"text":"Ventas","link":"https:\/\/www.danielpradilla.info\/blog\/category\/ventas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.danielpradilla.info\/blog\/wp-content\/uploads\/2012\/01\/finishing.jpeg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.danielpradilla.info\/blog\/wp-content\/uploads\/2012\/01\/finishing.jpeg?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.danielpradilla.info\/blog\/wp-content\/uploads\/2012\/01\/finishing.jpeg?resize=525%2C300 1.5x"},"classes":[]},{"id":1552,"url":"https:\/\/www.danielpradilla.info\/blog\/como-hacer-una-presentacion-efectiva-ii\/","url_meta":{"origin":1599,"position":2},"title":"C\u00c3\u00b3mo hacer una presentaci\u00c3\u00b3n efectiva, II","author":"Daniel Pradilla","date":"07\/12\/2010","format":false,"excerpt":"Lee la primera parte de este art\u00c3\u00adculo aqu\u00c3\u00ad Durante miles de a\u00c3\u00b1os la humanidad utiliz\u00c3\u00b3 la narrativa oral como principal medio para la divulgaci\u00c3\u00b3n de conocimiento. Casi todos comprendemos intuitivamente la importancia de saber contar una historia. Es algo que llevamos en nuestra programaci\u00c3\u00b3n. Si eso es as\u00c3\u00ad \u00bfpor qu\u00c3\u00a9\u2026","rel":"","context":"In &quot;Control de Proyectos&quot;","block_context":{"text":"Control de Proyectos","link":"https:\/\/www.danielpradilla.info\/blog\/category\/controldeproyectos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.danielpradilla.info\/blog\/wp-content\/uploads\/2010\/10\/6a00e55014bea188330133ef5befa4970b-320wi.jpeg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1668,"url":"https:\/\/www.danielpradilla.info\/blog\/6-tips-para-una-presentacion-cautivadora\/","url_meta":{"origin":1599,"position":3},"title":"6 Tips para una presentaci\u00c3\u00b3n cautivadora","author":"Daniel Pradilla","date":"17\/06\/2011","format":false,"excerpt":"\u00a0 \u00a0 Enf\u00c3\u00b3cate en entusiasmar a la gente. Ve al coraz\u00c3\u00b3n del mensaje. Reduce la presentaci\u00c3\u00b3n a 3 puntos que la audiencia debe entender. Cuenta una historia cautivadora. Resonate:, de Nancy Duarte, muestra como captura a una audiencia con una historia. As\u00c3\u00b3mbralos con palabras. Si no eres tan elocuente, busca\u2026","rel":"","context":"In &quot;Control de Proyectos&quot;","block_context":{"text":"Control de Proyectos","link":"https:\/\/www.danielpradilla.info\/blog\/category\/controldeproyectos\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1621,"url":"https:\/\/www.danielpradilla.info\/blog\/como-hacer-una-factura-en-cinco-minutos\/","url_meta":{"origin":1599,"position":4},"title":"C\u00c3\u00b3mo hacer una factura en cinco minutos","author":"Daniel Pradilla","date":"26\/03\/2011","format":false,"excerpt":"Todos nos hemos encontrado en esa situaci\u00c3\u00b3n: tenemos que hace una factura r\u00c3\u00a1pida que parezca profesional y legal, pero no tenemos el software para hacerlo. La gente de billable ha creado un sitio que es absolutamente obvio y f\u00c3\u00a1cil de usar. Permite imprimir facturas o salvarlas en PDF, cambiar la\u2026","rel":"","context":"In &quot;Ventas&quot;","block_context":{"text":"Ventas","link":"https:\/\/www.danielpradilla.info\/blog\/category\/ventas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.danielpradilla.info\/blog\/wp-content\/uploads\/2011\/03\/Screen-shot-2011-03-21-at-12.12.57-AM-300x209.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1658,"url":"https:\/\/www.danielpradilla.info\/blog\/vota-por-tu-presentacion-favorita\/","url_meta":{"origin":1599,"position":5},"title":"Vota por tu presentaci\u00c3\u00b3n favorita","author":"Daniel Pradilla","date":"21\/05\/2011","format":false,"excerpt":"Desde Abril de 2011, Microsoft est\u00c3\u00a1 haciendo el Powerpoint Slidefest, un concurso paras las mejores presentaciones creadas con Powerpoint. Una excelente iniciativa, \u00a1considerando el da\u00c3\u00b1o que Powerpoint le ha hecho al mundo! Mira\u00a0esta serie de videos sobre las cosas que se deben hacer y las que no se deben hacer.\u2026","rel":"","context":"In &quot;Control de Proyectos&quot;","block_context":{"text":"Control de Proyectos","link":"https:\/\/www.danielpradilla.info\/blog\/category\/controldeproyectos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.danielpradilla.info\/blog\/wp-content\/uploads\/2011\/05\/Screen-shot-2011-05-21-at-4.06.41-PM.png?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.danielpradilla.info\/blog\/wp-content\/uploads\/2011\/05\/Screen-shot-2011-05-21-at-4.06.41-PM.png?resize=350%2C200 1x, https:\/\/i0.wp.com\/www.danielpradilla.info\/blog\/wp-content\/uploads\/2011\/05\/Screen-shot-2011-05-21-at-4.06.41-PM.png?resize=525%2C300 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.danielpradilla.info\/blog\/wp-json\/wp\/v2\/posts\/1599","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.danielpradilla.info\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.danielpradilla.info\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.danielpradilla.info\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.danielpradilla.info\/blog\/wp-json\/wp\/v2\/comments?post=1599"}],"version-history":[{"count":0,"href":"https:\/\/www.danielpradilla.info\/blog\/wp-json\/wp\/v2\/posts\/1599\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.danielpradilla.info\/blog\/wp-json\/wp\/v2\/media?parent=1599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.danielpradilla.info\/blog\/wp-json\/wp\/v2\/categories?post=1599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.danielpradilla.info\/blog\/wp-json\/wp\/v2\/tags?post=1599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}